{"id":940,"date":"2023-04-20T11:52:04","date_gmt":"2023-04-20T17:52:04","guid":{"rendered":"https:\/\/masquenoticias.mx\/?p=940"},"modified":"2023-04-20T11:52:04","modified_gmt":"2023-04-20T17:52:04","slug":"gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores","status":"publish","type":"post","link":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/","title":{"rendered":"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores"},"content":{"rendered":"<p>La ma\u00f1ana de este jueves, la gobernadora Indira Vizca\u00edno Silva acudi\u00f3 a la entrega de mil 200 tarjetas de la Pensi\u00f3n para el Bienestar de las Personas Adultas Mayores (PAM) en el municipio de Colima. Cabe recordar que en la capital del estado ser\u00e1n entregadas 7 mil 161 tarjetas (cambio de BBVA), distribuidas en seis jornadas. De \u00e9stas, 274 beneficiarias y beneficiarios son de nueva incorporaci\u00f3n.<\/p>\n<p>La mandataria estatal record\u00f3 que est\u00e1 pensi\u00f3n ya es universal, debido a que muchas y muchos adultos mayores no recib\u00edan ning\u00fan tipo de beneficio, y aunque otros y otras s\u00ed lo obten\u00edan, era muy poco monto econ\u00f3mico.<\/p>\n<p>&#8220;Cuando arranc\u00f3 el gobierno del presidente de M\u00e9xico (Andr\u00e9s Manuel L\u00f3pez Obrador), esta pensi\u00f3n era de mil 160 pesos bimestrales y \u00e9l dijo que se iba a ir por lo menos al doble, o sea a 2,320 pesos por bimestre, pero ya va en el cu\u00e1druple -4 mil 800- y el pr\u00f3ximo a\u00f1o va a llegar a los 6,00 pesos&#8221;, enfatiz\u00f3 la titular del Poder Ejecutivo estatal.<\/p>\n<p>Vizca\u00edno Silva record\u00f3 que el presidente AMLO ya dej\u00f3 establecido en la Constituci\u00f3n que la pensi\u00f3n es un derecho, que est\u00e1 tendr\u00e1 que ir aumentando a\u00f1o con a\u00f1o y que nunca podr\u00e1 ser de menos, pensando en el beneficio de las personas adultas mayores de toda la Rep\u00fablica Mexicana.<\/p>\n<p>Por su parte, la delegada de Programas para el Bienestar del Gobierno de M\u00e9xico en Colima, Viridiana Valencia Vargas, record\u00f3 que cuando L\u00f3pez Obrador lleg\u00f3 al gobierno, se ten\u00eda un registro de 5 millones de personas adultas mayores con este tipo de pensi\u00f3n, y cuando el titular del Poder Ejecutivo federal decide hacerlo un derecho universal, este padr\u00f3n se increment\u00f3 a 11 millones de personas de 65 y m\u00e1s a\u00f1os de edad.<\/p>\n<p>&#8220;Ingresamos a 6 millones m\u00e1s de beneficiarias y beneficiarios, lo que nos demuestra que no era parejo, que no era para todas y todos, antes eta desde los 68 a\u00f1os de edad, ahora es desde los 65 a\u00f1os&#8221; expres\u00f3 la funcionaria federal Viri Valencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana de este jueves, la gobernadora Indira Vizca\u00edno Silva acudi\u00f3 a la entrega de mil 200 tarjetas de la Pensi\u00f3n para el Bienestar de las Personas Adultas Mayores (PAM) en el municipio de Colima. Cabe recordar que en la capital del estado ser\u00e1n entregadas 7 mil 161 tarjetas (cambio de BBVA), distribuidas en seis [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[72,26],"class_list":["post-940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-gobierno","tag-indira-vizcaino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores - M\u00e1s Que Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores - M\u00e1s Que Noticias\" \/>\n<meta property=\"og:description\" content=\"La ma\u00f1ana de este jueves, la gobernadora Indira Vizca\u00edno Silva acudi\u00f3 a la entrega de mil 200 tarjetas de la Pensi\u00f3n para el Bienestar de las Personas Adultas Mayores (PAM) en el municipio de Colima. Cabe recordar que en la capital del estado ser\u00e1n entregadas 7 mil 161 tarjetas (cambio de BBVA), distribuidas en seis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1s Que Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/masquenoticiascolima\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T17:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@edgartove\" \/>\n<meta name=\"twitter:site\" content=\"@edgartove\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622\"},\"headline\":\"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores\",\"datePublished\":\"2023-04-20T17:52:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\"},\"wordCount\":372,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/masquenoticias.mx\/#organization\"},\"image\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1\",\"keywords\":[\"Gobierno\",\"Indira Vizca\u00edno\"],\"articleSection\":[\"Estado\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\",\"url\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\",\"name\":\"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores - M\u00e1s Que Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/masquenoticias.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1\",\"datePublished\":\"2023-04-20T17:52:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/masquenoticias.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/masquenoticias.mx\/#website\",\"url\":\"https:\/\/masquenoticias.mx\/\",\"name\":\"M\u00e1s Que Noticias\",\"description\":\"Noticias de Colima, M\u00e9xico y el Mundo\",\"publisher\":{\"@id\":\"https:\/\/masquenoticias.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/masquenoticias.mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/masquenoticias.mx\/#organization\",\"name\":\"M\u00e1s Que Noticias\",\"url\":\"https:\/\/masquenoticias.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1\",\"width\":2560,\"height\":1656,\"caption\":\"M\u00e1s Que Noticias\"},\"image\":{\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/masquenoticiascolima\",\"https:\/\/x.com\/edgartove\",\"https:\/\/www.instagram.com\/masquenoticiascolima\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"http:\/\/masquenoticias.mx\"],\"url\":\"https:\/\/masquenoticias.mx\/index.php\/author\/edgartovegmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores - M\u00e1s Que Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/","og_locale":"es_MX","og_type":"article","og_title":"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores - M\u00e1s Que Noticias","og_description":"La ma\u00f1ana de este jueves, la gobernadora Indira Vizca\u00edno Silva acudi\u00f3 a la entrega de mil 200 tarjetas de la Pensi\u00f3n para el Bienestar de las Personas Adultas Mayores (PAM) en el municipio de Colima. Cabe recordar que en la capital del estado ser\u00e1n entregadas 7 mil 161 tarjetas (cambio de BBVA), distribuidas en seis [&hellip;]","og_url":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/","og_site_name":"M\u00e1s Que Noticias","article_publisher":"https:\/\/www.facebook.com\/masquenoticiascolima","article_published_time":"2023-04-20T17:52:04+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@edgartove","twitter_site":"@edgartove","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#article","isPartOf":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622"},"headline":"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores","datePublished":"2023-04-20T17:52:04+00:00","mainEntityOfPage":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/"},"wordCount":372,"commentCount":0,"publisher":{"@id":"https:\/\/masquenoticias.mx\/#organization"},"image":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1","keywords":["Gobierno","Indira Vizca\u00edno"],"articleSection":["Estado"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/","url":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/","name":"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores - M\u00e1s Que Noticias","isPartOf":{"@id":"https:\/\/masquenoticias.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage"},"image":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1","datePublished":"2023-04-20T17:52:04+00:00","breadcrumb":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#primaryimage","url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1","contentUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/masquenoticias.mx\/index.php\/2023\/04\/20\/gobernadora-acudio-a-entrega-de-1200-tarjetas-de-la-pension-para-el-bienestar-de-personas-adultas-mayores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/masquenoticias.mx\/"},{"@type":"ListItem","position":2,"name":"Gobernadora acudi\u00f3 a entrega de 1,200 tarjetas de la Pensi\u00f3n para el Bienestar de Personas Adultas Mayores"}]},{"@type":"WebSite","@id":"https:\/\/masquenoticias.mx\/#website","url":"https:\/\/masquenoticias.mx\/","name":"M\u00e1s Que Noticias","description":"Noticias de Colima, M\u00e9xico y el Mundo","publisher":{"@id":"https:\/\/masquenoticias.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masquenoticias.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/masquenoticias.mx\/#organization","name":"M\u00e1s Que Noticias","url":"https:\/\/masquenoticias.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1","contentUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1","width":2560,"height":1656,"caption":"M\u00e1s Que Noticias"},"image":{"@id":"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/masquenoticiascolima","https:\/\/x.com\/edgartove","https:\/\/www.instagram.com\/masquenoticiascolima\/"]},{"@type":"Person","@id":"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masquenoticias.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"sameAs":["http:\/\/masquenoticias.mx"],"url":"https:\/\/masquenoticias.mx\/index.php\/author\/edgartovegmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1","blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=150%2C150&ssl=1",150,150,true],"full":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1",1280,853,false]},"categories_names":{"24":{"name":"Estado","link":"https:\/\/masquenoticias.mx\/index.php\/category\/estado\/"}},"tags_names":{"72":{"name":"Gobierno","link":"https:\/\/masquenoticias.mx\/index.php\/tag\/gobierno\/"},"26":{"name":"Indira Vizca\u00edno","link":"https:\/\/masquenoticias.mx\/index.php\/tag\/indira-vizcaino\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=150%2C150&ssl=1",150,150,true],"cvmm-medium":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=300%2C300&ssl=1",300,300,true],"cvmm-medium-plus":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=305%2C207&ssl=1",305,207,true],"cvmm-portrait":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=400%2C600&ssl=1",400,600,true],"cvmm-medium-square":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=600%2C600&ssl=1",600,600,true],"cvmm-large":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=1024%2C853&ssl=1",1024,853,true],"cvmm-small":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?resize=130%2C95&ssl=1",130,95,true],"full":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-20-at-11.48.16-AM.jpeg?fit=1280%2C853&ssl=1",1280,853,false]},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf7pkt-fa","_links":{"self":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=940"}],"version-history":[{"count":0,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/941"}],"wp:attachment":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}