{"id":22842,"date":"2026-05-12T20:16:13","date_gmt":"2026-05-13T02:16:13","guid":{"rendered":"https:\/\/masquenoticias.mx\/?p=22842"},"modified":"2026-05-12T20:16:13","modified_gmt":"2026-05-13T02:16:13","slug":"entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria","status":"publish","type":"post","link":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/","title":{"rendered":"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda"},"content":{"rendered":"<p>Este martes 12 de mayo, el H. Congreso del Estado de Colima entreg\u00f3, en sesi\u00f3n solemne, el Premio Estatal de Enfermer\u00eda 2026 a Blanca Judith \u00c1vila Flores, Jos\u00e9 Guillermo Solorio Hern\u00e1ndez, Juan Carlos Ponce Rodr\u00edguez y Guillermo Silva Maga\u00f1a, por su destacada labor en esta \u00e1rea de la salud.<\/p>\n<p>La presidenta de la Comisi\u00f3n de Salud y Deporte, Karen Jurado Escamilla, expres\u00f3 que para ella es un honor dirigirse a las personas ganadoras, no solo como diputada, sino como enfermera de profesi\u00f3n, pues m\u00e1s all\u00e1 de una premiaci\u00f3n, es un reconocimiento a la labor, esfuerzo, sensibilidad, paciencia y el enorme compromiso para con los pacientes. A\u00f1adi\u00f3 que, sin duda las personas galardonadas ponen el alto el nombre de Colima.<\/p>\n<p>En su participaci\u00f3n, la diputada Evangelina Bustamante, presidenta de la comisi\u00f3n de Educaci\u00f3n, Cultura y Ciencia, mencion\u00f3 que desde el Congreso del Estado, se entiende que hablar de salud tambi\u00e9n es hablar de justicia, dignidad y cuidados; por eso, las diputadas y diputados, tienen la responsabilidad de legislar para construir una verdadera sociedad de cuidados, donde el Estado y la comunidad tambi\u00e9n reconozcan y protejan a quienes todos los d\u00edas cuidan de la poblaci\u00f3n.<\/p>\n<p>Luego de estas intervenciones, Blanca Judith \u00c1vila Flores, ganadora del M\u00e9rito en Enfermer\u00eda Primer Nivel de Atenci\u00f3n, Jos\u00e9 Guillermo Solorio Hern\u00e1ndez, galardonado en la categor\u00eda de Enfermer\u00eda de Segundo y Tercer Nivel de Atenci\u00f3n, Juan Carlos Ponce Rodr\u00edguez, reconocido en la categor\u00eda de Gesti\u00f3n en enfermer\u00eda y mejora de procesos y Guillermo Silva Maga\u00f1a, merecedor del Premio al M\u00e9rito de Enfermer\u00eda, Investigaci\u00f3n y Docencia, recibieron cada uno su distinci\u00f3n.<\/p>\n<p>Posteriormente, la presidenta de la mesa directiva del Congreso, Martha Elia Far\u00edas R\u00edos, se\u00f1al\u00f3 que las y los profesionales de enfermer\u00eda no solo ejecutan procedimientos m\u00e9dicos; acompa\u00f1an, consuelan, orientan y dignifican cada proceso de atenci\u00f3n. \u201cSu labor trasciende la t\u00e9cnica, para convertirse en algo profundamente humano, pues las enfermeras y los enfermeros tienen la capacidad de transformar el miedo en esperanza, la angustia en calma, la enfermedad en un camino acompa\u00f1ado\u201d.<\/p>\n<p>En representaci\u00f3n de la Gobernadora del Estado, Indira Vizca\u00edno Silva, el titular de la Secretar\u00eda de Salud, V\u00edctor Manuel Torrero Enr\u00edquez, destac\u00f3 que las personas galardonadas, no solamente figuran por su excelencia t\u00e9cnica, sino tambi\u00e9n por su calidad humana. Reconoce tambi\u00e9n a las miles de enfermeras y enfermeros que se encuentran en cada centro de salud en comunidades, colonias y en cada rinc\u00f3n, pues son la columna vertebral del sistema de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 12 de mayo, el H. Congreso del Estado de Colima entreg\u00f3, en sesi\u00f3n solemne, el Premio Estatal de Enfermer\u00eda 2026 a Blanca Judith \u00c1vila Flores, Jos\u00e9 Guillermo Solorio Hern\u00e1ndez, Juan Carlos Ponce Rodr\u00edguez y Guillermo Silva Maga\u00f1a, por su destacada labor en esta \u00e1rea de la salud. La presidenta de la Comisi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32],"tags":[628],"class_list":["post-22842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-congreso-colima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda - M\u00e1s Que Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda - M\u00e1s Que Noticias\" \/>\n<meta property=\"og:description\" content=\"Este martes 12 de mayo, el H. Congreso del Estado de Colima entreg\u00f3, en sesi\u00f3n solemne, el Premio Estatal de Enfermer\u00eda 2026 a Blanca Judith \u00c1vila Flores, Jos\u00e9 Guillermo Solorio Hern\u00e1ndez, Juan Carlos Ponce Rodr\u00edguez y Guillermo Silva Maga\u00f1a, por su destacada labor en esta \u00e1rea de la salud. La presidenta de la Comisi\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1s Que Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/masquenoticiascolima\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T02:16:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@edgartove\" \/>\n<meta name=\"twitter:site\" content=\"@edgartove\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622\"},\"headline\":\"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda\",\"datePublished\":\"2026-05-13T02:16:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/masquenoticias.mx\/#organization\"},\"image\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1\",\"keywords\":[\"Congreso Colima\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\",\"url\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\",\"name\":\"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda - M\u00e1s Que Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/masquenoticias.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1\",\"datePublished\":\"2026-05-13T02:16:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/masquenoticias.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/masquenoticias.mx\/#website\",\"url\":\"https:\/\/masquenoticias.mx\/\",\"name\":\"M\u00e1s Que Noticias\",\"description\":\"Noticias de Colima, M\u00e9xico y el Mundo\",\"publisher\":{\"@id\":\"https:\/\/masquenoticias.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/masquenoticias.mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/masquenoticias.mx\/#organization\",\"name\":\"M\u00e1s Que Noticias\",\"url\":\"https:\/\/masquenoticias.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1\",\"width\":2560,\"height\":1656,\"caption\":\"M\u00e1s Que Noticias\"},\"image\":{\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/masquenoticiascolima\",\"https:\/\/x.com\/edgartove\",\"https:\/\/www.instagram.com\/masquenoticiascolima\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/masquenoticias.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"http:\/\/masquenoticias.mx\"],\"url\":\"https:\/\/masquenoticias.mx\/index.php\/author\/edgartovegmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda - M\u00e1s Que Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/","og_locale":"es_MX","og_type":"article","og_title":"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda - M\u00e1s Que Noticias","og_description":"Este martes 12 de mayo, el H. Congreso del Estado de Colima entreg\u00f3, en sesi\u00f3n solemne, el Premio Estatal de Enfermer\u00eda 2026 a Blanca Judith \u00c1vila Flores, Jos\u00e9 Guillermo Solorio Hern\u00e1ndez, Juan Carlos Ponce Rodr\u00edguez y Guillermo Silva Maga\u00f1a, por su destacada labor en esta \u00e1rea de la salud. La presidenta de la Comisi\u00f3n de [&hellip;]","og_url":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/","og_site_name":"M\u00e1s Que Noticias","article_publisher":"https:\/\/www.facebook.com\/masquenoticiascolima","article_published_time":"2026-05-13T02:16:13+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@edgartove","twitter_site":"@edgartove","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#article","isPartOf":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622"},"headline":"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda","datePublished":"2026-05-13T02:16:13+00:00","mainEntityOfPage":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/masquenoticias.mx\/#organization"},"image":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1","keywords":["Congreso Colima"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/","url":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/","name":"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda - M\u00e1s Que Noticias","isPartOf":{"@id":"https:\/\/masquenoticias.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage"},"image":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1","datePublished":"2026-05-13T02:16:13+00:00","breadcrumb":{"@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#primaryimage","url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1","contentUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/masquenoticias.mx\/index.php\/2026\/05\/12\/entrega-congreso-del-estado-premio-estatal-2026-a-cuatro-profesionales-de-la-enfermeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/masquenoticias.mx\/"},{"@type":"ListItem","position":2,"name":"Entrega Congreso del Estado premio estatal 2026 a cuatro profesionales de la enfermer\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/masquenoticias.mx\/#website","url":"https:\/\/masquenoticias.mx\/","name":"M\u00e1s Que Noticias","description":"Noticias de Colima, M\u00e9xico y el Mundo","publisher":{"@id":"https:\/\/masquenoticias.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masquenoticias.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/masquenoticias.mx\/#organization","name":"M\u00e1s Que Noticias","url":"https:\/\/masquenoticias.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1","contentUrl":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2024\/04\/IMG_0004.png?fit=2560%2C1656&ssl=1","width":2560,"height":1656,"caption":"M\u00e1s Que Noticias"},"image":{"@id":"https:\/\/masquenoticias.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/masquenoticiascolima","https:\/\/x.com\/edgartove","https:\/\/www.instagram.com\/masquenoticiascolima\/"]},{"@type":"Person","@id":"https:\/\/masquenoticias.mx\/#\/schema\/person\/544d19989ef23d34615f691f7a96e622","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masquenoticias.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fcc926d5b058d3f3d52d95b4d05dd58?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"sameAs":["http:\/\/masquenoticias.mx"],"url":"https:\/\/masquenoticias.mx\/index.php\/author\/edgartovegmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1","blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=150%2C150&ssl=1",150,150,true],"full":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1",1600,1066,false]},"categories_names":{"32":{"name":"Pol\u00edtica","link":"https:\/\/masquenoticias.mx\/index.php\/category\/politica\/"}},"tags_names":{"628":{"name":"Congreso Colima","link":"https:\/\/masquenoticias.mx\/index.php\/tag\/congreso-colima\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=150%2C150&ssl=1",150,150,true],"cvmm-medium":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=300%2C300&ssl=1",300,300,true],"cvmm-medium-plus":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=305%2C207&ssl=1",305,207,true],"cvmm-portrait":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=400%2C600&ssl=1",400,600,true],"cvmm-medium-square":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=600%2C600&ssl=1",600,600,true],"cvmm-large":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=1024%2C1024&ssl=1",1024,1024,true],"cvmm-small":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?resize=130%2C95&ssl=1",130,95,true],"full":["https:\/\/i0.wp.com\/masquenoticias.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-12.54.26-PM.jpeg?fit=1600%2C1066&ssl=1",1600,1066,false]},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf7pkt-5Wq","_links":{"self":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/22842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=22842"}],"version-history":[{"count":1,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/22842\/revisions"}],"predecessor-version":[{"id":22844,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/22842\/revisions\/22844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/22843"}],"wp:attachment":[{"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=22842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=22842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masquenoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=22842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}